{"id":360,"date":"2024-04-17T02:03:22","date_gmt":"2024-04-17T02:03:22","guid":{"rendered":"https:\/\/bedson.com\/wp\/?post_type=catalogo-productos&#038;p=360"},"modified":"2024-05-23T11:48:26","modified_gmt":"2024-05-23T11:48:26","slug":"sinatop","status":"publish","type":"catalogo-productos","link":"https:\/\/bedson.com\/en\/catalogo-productos\/sinatop\/","title":{"rendered":"SINATOP\u00ae AV\u00cdCOLA"},"content":{"rendered":"","protected":false},"template":"","categorias-de-especies":[4],"class_list":["post-360","catalogo-productos","type-catalogo-productos","status-publish","hentry","categorias-de-especies-productos-division-avicola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SINATOP\u00ae AV\u00cdCOLA - Bedson SA<\/title>\n<meta name=\"description\" content=\"SINATOP\u00ae es un producto de alta calidad para la salud animal, formulado para mejorar la resistencia y el bienestar general de los animales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bedson.com\/en\/catalogo-productos\/sinatop\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SINATOP\u00ae AV\u00cdCOLA - Bedson SA\" \/>\n<meta property=\"og:description\" content=\"SINATOP\u00ae es un producto de alta calidad para la salud animal, formulado para mejorar la resistencia y el bienestar general de los animales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bedson.com\/en\/catalogo-productos\/sinatop\/\" \/>\n<meta property=\"og:site_name\" content=\"Bedson SA\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T11:48:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bedson.com\\\/catalogo-productos\\\/sinatop\\\/\",\"url\":\"https:\\\/\\\/bedson.com\\\/catalogo-productos\\\/sinatop\\\/\",\"name\":\"SINATOP\u00ae AV\u00cdCOLA - Bedson SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bedson.com\\\/#website\"},\"datePublished\":\"2024-04-17T02:03:22+00:00\",\"dateModified\":\"2024-05-23T11:48:26+00:00\",\"description\":\"SINATOP\u00ae es un producto de alta calidad para la salud animal, formulado para mejorar la resistencia y el bienestar general de los animales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bedson.com\\\/catalogo-productos\\\/sinatop\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bedson.com\\\/catalogo-productos\\\/sinatop\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bedson.com\\\/catalogo-productos\\\/sinatop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/bedson.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/bedson.com\\\/catalogo-productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SINATOP\u00ae AV\u00cdCOLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bedson.com\\\/#website\",\"url\":\"https:\\\/\\\/bedson.com\\\/\",\"name\":\"Bedson SA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bedson.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bedson.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bedson.com\\\/#organization\",\"name\":\"Bedson SA\",\"url\":\"https:\\\/\\\/bedson.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bedson.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bedson.com\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-logo-bedson-copia.webp\",\"contentUrl\":\"https:\\\/\\\/bedson.com\\\/wp\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-logo-bedson-copia.webp\",\"width\":101,\"height\":98,\"caption\":\"Bedson SA\"},\"image\":{\"@id\":\"https:\\\/\\\/bedson.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SINATOP\u00ae AV\u00cdCOLA - Bedson SA","description":"SINATOP\u00ae es un producto de alta calidad para la salud animal, formulado para mejorar la resistencia y el bienestar general de los animales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bedson.com\/en\/catalogo-productos\/sinatop\/","og_locale":"en_US","og_type":"article","og_title":"SINATOP\u00ae AV\u00cdCOLA - Bedson SA","og_description":"SINATOP\u00ae es un producto de alta calidad para la salud animal, formulado para mejorar la resistencia y el bienestar general de los animales.","og_url":"https:\/\/bedson.com\/en\/catalogo-productos\/sinatop\/","og_site_name":"Bedson SA","article_modified_time":"2024-05-23T11:48:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bedson.com\/catalogo-productos\/sinatop\/","url":"https:\/\/bedson.com\/catalogo-productos\/sinatop\/","name":"SINATOP\u00ae AV\u00cdCOLA - Bedson SA","isPartOf":{"@id":"https:\/\/bedson.com\/#website"},"datePublished":"2024-04-17T02:03:22+00:00","dateModified":"2024-05-23T11:48:26+00:00","description":"SINATOP\u00ae es un producto de alta calidad para la salud animal, formulado para mejorar la resistencia y el bienestar general de los animales.","breadcrumb":{"@id":"https:\/\/bedson.com\/catalogo-productos\/sinatop\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bedson.com\/catalogo-productos\/sinatop\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bedson.com\/catalogo-productos\/sinatop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/bedson.com\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/bedson.com\/catalogo-productos\/"},{"@type":"ListItem","position":3,"name":"SINATOP\u00ae AV\u00cdCOLA"}]},{"@type":"WebSite","@id":"https:\/\/bedson.com\/#website","url":"https:\/\/bedson.com\/","name":"Bedson SA","description":"","publisher":{"@id":"https:\/\/bedson.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bedson.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bedson.com\/#organization","name":"Bedson SA","url":"https:\/\/bedson.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bedson.com\/#\/schema\/logo\/image\/","url":"https:\/\/bedson.com\/wp\/wp-content\/uploads\/2024\/04\/cropped-logo-bedson-copia.webp","contentUrl":"https:\/\/bedson.com\/wp\/wp-content\/uploads\/2024\/04\/cropped-logo-bedson-copia.webp","width":101,"height":98,"caption":"Bedson SA"},"image":{"@id":"https:\/\/bedson.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bedson.com\/en\/wp-json\/wp\/v2\/catalogo-productos\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bedson.com\/en\/wp-json\/wp\/v2\/catalogo-productos"}],"about":[{"href":"https:\/\/bedson.com\/en\/wp-json\/wp\/v2\/types\/catalogo-productos"}],"wp:attachment":[{"href":"https:\/\/bedson.com\/en\/wp-json\/wp\/v2\/media?parent=360"}],"wp:term":[{"taxonomy":"categorias-de-especies","embeddable":true,"href":"https:\/\/bedson.com\/en\/wp-json\/wp\/v2\/categorias-de-especies?post=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}